{"id":64730,"date":"2023-12-22T09:26:22","date_gmt":"2023-12-22T08:26:22","guid":{"rendered":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg"},"modified":"2023-12-22T09:26:22","modified_gmt":"2023-12-22T08:26:22","slug":"renna_natale_bdc-2","status":"inherit","type":"attachment","link":"https:\/\/www.bancadellacalce.it\/bdc\/la-banca-della-calce-2-2-2-2\/renna_natale_bdc-2\/","title":{"rendered":"renna_natale_bdc"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-64730","attachment","type-attachment","status-inherit","hentry","entry","no-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>renna_natale_bdc - La banca della calce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"renna_natale_bdc - La banca della calce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"La banca della calce\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Banca-della-Calce-223667067649398\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"822\" \/>\n\t<meta property=\"og:image:height\" content=\"822\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/renna_natale_bdc-1.jpg\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/renna_natale_bdc-1.jpg\",\"name\":\"renna_natale_bdc - La banca della calce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#website\"},\"datePublished\":\"2023-12-22T08:26:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/renna_natale_bdc-1.jpg#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/renna_natale_bdc-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/renna_natale_bdc-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Banca della Calce &#8211; ENG\",\"item\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/?lang=en\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"renna_natale_bdc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#website\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/\",\"name\":\"La banca della calce\",\"description\":\"Costruire per natura\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#organization\",\"name\":\"La Banca della Calce\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/logo-labancadellacalce.png\",\"contentUrl\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/logo-labancadellacalce.png\",\"width\":729,\"height\":125,\"caption\":\"La Banca della Calce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Banca-della-Calce-223667067649398\\\/\",\"https:\\\/\\\/www.instagram.com\\\/labancadellacalce\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/19183447\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"renna_natale_bdc - La banca della calce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg","og_locale":"it_IT","og_type":"article","og_title":"renna_natale_bdc - La banca della calce","og_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg","og_site_name":"La banca della calce","article_publisher":"https:\/\/www.facebook.com\/La-Banca-della-Calce-223667067649398\/","og_image":[{"width":822,"height":822,"url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg","url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg","name":"renna_natale_bdc - La banca della calce","isPartOf":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/#website"},"datePublished":"2023-12-22T08:26:22+00:00","breadcrumb":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bancadellacalce.it\/bdc\/"},{"@type":"ListItem","position":2,"name":"La Banca della Calce &#8211; ENG","item":"https:\/\/www.bancadellacalce.it\/bdc\/?lang=en"},{"@type":"ListItem","position":3,"name":"renna_natale_bdc"}]},{"@type":"WebSite","@id":"https:\/\/www.bancadellacalce.it\/bdc\/#website","url":"https:\/\/www.bancadellacalce.it\/bdc\/","name":"La banca della calce","description":"Costruire per natura","publisher":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bancadellacalce.it\/bdc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.bancadellacalce.it\/bdc\/#organization","name":"La Banca della Calce","url":"https:\/\/www.bancadellacalce.it\/bdc\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bancadellacalce.it\/bdc\/#\/schema\/logo\/image\/","url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2016\/01\/logo-labancadellacalce.png","contentUrl":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2016\/01\/logo-labancadellacalce.png","width":729,"height":125,"caption":"La Banca della Calce"},"image":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Banca-della-Calce-223667067649398\/","https:\/\/www.instagram.com\/labancadellacalce\/","https:\/\/www.linkedin.com\/company\/19183447"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-300x300.jpg 300w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-150x150.jpg 150w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-768x768.jpg 768w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-600x600.jpg 600w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-100x100.jpg 100w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-50x50.jpg 50w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg 822w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":822,"height":822,"file":"2023\/12\/renna_natale_bdc-1.jpg","filesize":45231,"sizes":{"medium":{"file":"renna_natale_bdc-1-300x300.jpg","width":300,"height":300,"filesize":10710,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-300x300.jpg"},"thumbnail":{"file":"renna_natale_bdc-1-150x150.jpg","width":150,"height":150,"filesize":4601,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-150x150.jpg"},"medium_large":{"file":"renna_natale_bdc-1-768x768.jpg","width":768,"height":768,"filesize":38970,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-768x768.jpg"},"woocommerce_thumbnail":{"file":"renna_natale_bdc-1-300x300.jpg","width":300,"height":300,"filesize":10710,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg"},"woocommerce_single":{"file":"renna_natale_bdc-1-600x600.jpg","width":600,"height":600,"filesize":27468,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg"},"woocommerce_gallery_thumbnail":{"file":"renna_natale_bdc-1-100x100.jpg","width":100,"height":100,"filesize":3061,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-100x100.jpg"},"shop_thumbnail":{"file":"renna_natale_bdc-1-100x100.jpg","width":100,"height":100,"filesize":3061,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-100x100.jpg"},"variation_swatches_image_size":{"file":"renna_natale_bdc-1-50x50.jpg","width":50,"height":50,"filesize":1814,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-50x50.jpg"},"variation_swatches_tooltip_size":{"file":"renna_natale_bdc-1-100x100.jpg","width":100,"height":100,"filesize":3061,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1-100x100.jpg"},"full":{"file":"renna_natale_bdc-1.jpg","width":822,"height":822,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":16392,"source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2023\/12\/renna_natale_bdc-1.jpg","_links":{"self":[{"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/media\/64730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/comments?post=64730"}]}}