{"id":43748,"date":"2021-09-29T17:01:39","date_gmt":"2021-09-29T15:01:39","guid":{"rendered":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg"},"modified":"2021-09-29T17:01:55","modified_gmt":"2021-09-29T15:01:55","slug":"casa-paglia-e-calcecanapa-2","status":"inherit","type":"attachment","link":"https:\/\/www.bancadellacalce.it\/bdc\/casa-paglia-e-calcecanapa-2\/","title":{"rendered":"casa-paglia-e-calcecanapa"},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-43748","attachment","type-attachment","status-inherit","hentry","entry","no-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>casa-paglia-e-calcecanapa - La banca della calce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"casa-paglia-e-calcecanapa - La banca della calce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg\" \/>\n<meta property=\"og:site_name\" content=\"La banca della calce\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Banca-della-Calce-223667067649398\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-29T15:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/casa-paglia-e-calcecanapa.jpg\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/casa-paglia-e-calcecanapa.jpg\",\"name\":\"casa-paglia-e-calcecanapa - La banca della calce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#website\"},\"datePublished\":\"2021-09-29T15:01:39+00:00\",\"dateModified\":\"2021-09-29T15:01:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/casa-paglia-e-calcecanapa.jpg#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/casa-paglia-e-calcecanapa.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/casa-paglia-e-calcecanapa.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"casa-paglia-e-calcecanapa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#website\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/\",\"name\":\"La banca della calce\",\"description\":\"Costruire per natura\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#organization\",\"name\":\"La Banca della Calce\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/logo-labancadellacalce.png\",\"contentUrl\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/logo-labancadellacalce.png\",\"width\":729,\"height\":125,\"caption\":\"La Banca della Calce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bancadellacalce.it\\\/bdc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Banca-della-Calce-223667067649398\\\/\",\"https:\\\/\\\/www.instagram.com\\\/labancadellacalce\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/19183447\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"casa-paglia-e-calcecanapa - La banca della calce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg","og_locale":"it_IT","og_type":"article","og_title":"casa-paglia-e-calcecanapa - La banca della calce","og_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg","og_site_name":"La banca della calce","article_publisher":"https:\/\/www.facebook.com\/La-Banca-della-Calce-223667067649398\/","article_modified_time":"2021-09-29T15:01:55+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg","url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg","name":"casa-paglia-e-calcecanapa - La banca della calce","isPartOf":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/#website"},"datePublished":"2021-09-29T15:01:39+00:00","dateModified":"2021-09-29T15:01:55+00:00","breadcrumb":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bancadellacalce.it\/bdc\/"},{"@type":"ListItem","position":2,"name":"casa-paglia-e-calcecanapa"}]},{"@type":"WebSite","@id":"https:\/\/www.bancadellacalce.it\/bdc\/#website","url":"https:\/\/www.bancadellacalce.it\/bdc\/","name":"La banca della calce","description":"Costruire per natura","publisher":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bancadellacalce.it\/bdc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.bancadellacalce.it\/bdc\/#organization","name":"La Banca della Calce","url":"https:\/\/www.bancadellacalce.it\/bdc\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bancadellacalce.it\/bdc\/#\/schema\/logo\/image\/","url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2016\/01\/logo-labancadellacalce.png","contentUrl":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2016\/01\/logo-labancadellacalce.png","width":729,"height":125,"caption":"La Banca della Calce"},"image":{"@id":"https:\/\/www.bancadellacalce.it\/bdc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Banca-della-Calce-223667067649398\/","https:\/\/www.instagram.com\/labancadellacalce\/","https:\/\/www.linkedin.com\/company\/19183447"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"esempio casa in paglia\" srcset=\"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-225x300.jpg 225w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-768x1024.jpg 768w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-1152x1536.jpg 1152w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-600x800.jpg 600w, https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"esempio casa in paglia","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":1600,"file":"2021\/09\/casa-paglia-e-calcecanapa.jpg","sizes":{"medium":{"file":"casa-paglia-e-calcecanapa-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-225x300.jpg"},"large":{"file":"casa-paglia-e-calcecanapa-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-768x1024.jpg"},"thumbnail":{"file":"casa-paglia-e-calcecanapa-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-150x150.jpg"},"medium_large":{"file":"casa-paglia-e-calcecanapa-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-768x1024.jpg"},"1536x1536":{"file":"casa-paglia-e-calcecanapa-1152x1536.jpg","width":1152,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-1152x1536.jpg"},"woocommerce_thumbnail":{"file":"casa-paglia-e-calcecanapa-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg"},"woocommerce_single":{"file":"casa-paglia-e-calcecanapa-600x800.jpg","width":600,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg"},"woocommerce_gallery_thumbnail":{"file":"casa-paglia-e-calcecanapa-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-100x100.jpg"},"shop_thumbnail":{"file":"casa-paglia-e-calcecanapa-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa-100x100.jpg"},"full":{"file":"casa-paglia-e-calcecanapa.jpg","width":1200,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2021-10-01 21:55:57","thumbsOpt":7,"thumbsOptList":["casa-paglia-e-calcecanapa-225x300.jpg","casa-paglia-e-calcecanapa-768x1024.jpg","casa-paglia-e-calcecanapa-150x150.jpg","casa-paglia-e-calcecanapa-1152x1536.jpg","casa-paglia-e-calcecanapa-300x300.jpg","casa-paglia-e-calcecanapa-600x800.jpg","casa-paglia-e-calcecanapa-100x100.jpg"],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"66.26"},"post":null,"source_url":"https:\/\/www.bancadellacalce.it\/bdc\/wp-content\/uploads\/2021\/09\/casa-paglia-e-calcecanapa.jpg","_links":{"self":[{"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/media\/43748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bancadellacalce.it\/bdc\/wp-json\/wp\/v2\/comments?post=43748"}]}}